{"id":18921,"date":"2024-11-14T17:32:51","date_gmt":"2024-11-14T17:32:51","guid":{"rendered":"https:\/\/www.proalps.ch\/?page_id=18921"},"modified":"2026-01-19T08:06:50","modified_gmt":"2026-01-19T08:06:50","slug":"population","status":"publish","type":"page","link":"https:\/\/proalps.ch\/fr\/proteger-les-alpes\/population\/","title":{"rendered":"La population des Alpes"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":27,"featured_media":0,"parent":18792,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_seopress_titles_title":"La population des Alpes","_seopress_titles_desc":"Les Alpes servent de patrie et d\u2019espace de travail, de d\u00e9tente et de culture pour beaucoup d\u2019entre nous. Prot\u00e9geons ensemble l\u2019espace de vie alpin !","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"La population des Alpes | Pro Alps","_seopress_social_fb_desc":"Les Alpes servent de patrie et d\u2019espace de travail, de d\u00e9tente et de culture pour beaucoup d\u2019entre nous. Prot\u00e9geons ensemble l\u2019espace de vie alpin !","_seopress_social_fb_img":"https:\/\/www.proalps.ch\/wp-content\/uploads\/2024\/10\/Furkahorn1-Silvan-Gnos.jpg","_seopress_social_fb_img_attachment_id":13856,"_seopress_social_fb_img_width":2900,"_seopress_social_fb_img_height":1933,"_seopress_social_twitter_title":"La population des Alpes | Pro Alps","_seopress_social_twitter_desc":"Les Alpes servent de patrie et d\u2019espace de travail, de d\u00e9tente et de culture pour beaucoup d\u2019entre nous. Prot\u00e9geons ensemble l\u2019espace de vie alpin !","_seopress_social_twitter_img":"https:\/\/www.proalps.ch\/wp-content\/uploads\/2024\/10\/Furkahorn1-Silvan-Gnos.jpg","_seopress_social_twitter_img_attachment_id":13856,"_seopress_social_twitter_img_width":2900,"_seopress_social_twitter_img_height":1933,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"both","_seopress_redirections_param":"","_seopress_redirections_type":301,"_seopress_analysis_target_kw":"","footnotes":""},"wf_page_folders":[87,86],"class_list":["post-18921","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/proalps.ch\/fr\/wp-json\/wp\/v2\/pages\/18921","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/proalps.ch\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/proalps.ch\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/proalps.ch\/fr\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/proalps.ch\/fr\/wp-json\/wp\/v2\/comments?post=18921"}],"version-history":[{"count":12,"href":"https:\/\/proalps.ch\/fr\/wp-json\/wp\/v2\/pages\/18921\/revisions"}],"predecessor-version":[{"id":31277,"href":"https:\/\/proalps.ch\/fr\/wp-json\/wp\/v2\/pages\/18921\/revisions\/31277"}],"up":[{"embeddable":true,"href":"https:\/\/proalps.ch\/fr\/wp-json\/wp\/v2\/pages\/18792"}],"wp:attachment":[{"href":"https:\/\/proalps.ch\/fr\/wp-json\/wp\/v2\/media?parent=18921"}],"wp:term":[{"taxonomy":"wf_page_folders","embeddable":true,"href":"https:\/\/proalps.ch\/fr\/wp-json\/wp\/v2\/wf_page_folders?post=18921"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}