{"id":24971,"date":"2025-03-27T12:26:27","date_gmt":"2025-03-27T12:26:27","guid":{"rendered":"https:\/\/proalps.ch\/?p=24971"},"modified":"2025-03-27T12:48:34","modified_gmt":"2025-03-27T12:48:34","slug":"controle-du-trafic-lourd-2024","status":"publish","type":"post","link":"https:\/\/proalps.ch\/fr\/controle-du-trafic-lourd-2024\/","title":{"rendered":"Les chiffres actuels sur le contr\u00f4le du trafic lourd inqui\u00e8tent"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":27,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_seopress_titles_title":"Les chiffres sur le contr\u00f4le du trafic lourd inqui\u00e8tent","_seopress_titles_desc":"Le nombre de v\u00e9hicules d\u00e9fectueux sur les routes suisses augmente tandis que le nombre de contr\u00f4les mobiles effectu\u00e9s est en baisse.","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"none","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"Les chiffres actuels sur le contr\u00f4le du trafic lourd inqui\u00e8tent","_seopress_social_fb_desc":"Le nombre de v\u00e9hicules d\u00e9fectueux sur les routes suisses augmente tandis que le nombre de contr\u00f4les mobiles effectu\u00e9s est en baisse.","_seopress_social_fb_img":"https:\/\/proalps.ch\/wp-content\/uploads\/2025\/03\/SVZ_1377368_Valentin-Luthiger_web-1.jpg","_seopress_social_fb_img_attachment_id":24959,"_seopress_social_fb_img_width":2880,"_seopress_social_fb_img_height":1920,"_seopress_social_twitter_title":"Les chiffres actuels sur le contr\u00f4le du trafic lourd inqui\u00e8tent","_seopress_social_twitter_desc":"Le nombre de v\u00e9hicules d\u00e9fectueux sur les routes suisses augmente tandis que le nombre de contr\u00f4les mobiles effectu\u00e9s est en baisse.","_seopress_social_twitter_img":"https:\/\/proalps.ch\/wp-content\/uploads\/2025\/03\/SVZ_1377368_Valentin-Luthiger_web-1.jpg","_seopress_social_twitter_img_attachment_id":24959,"_seopress_social_twitter_img_width":2880,"_seopress_social_twitter_img_height":1920,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"both","_seopress_redirections_param":"","_seopress_redirections_type":301,"_seopress_analysis_target_kw":"","footnotes":""},"categories":[97,124],"tags":[],"wf_post_folders":[],"class_list":["post-24971","post","type-post","status-publish","format-standard","hentry","category-communique-de-presse","category-securite-et-controles"],"acf":[],"_links":{"self":[{"href":"https:\/\/proalps.ch\/fr\/wp-json\/wp\/v2\/posts\/24971","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/proalps.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/proalps.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/proalps.ch\/fr\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/proalps.ch\/fr\/wp-json\/wp\/v2\/comments?post=24971"}],"version-history":[{"count":6,"href":"https:\/\/proalps.ch\/fr\/wp-json\/wp\/v2\/posts\/24971\/revisions"}],"predecessor-version":[{"id":24979,"href":"https:\/\/proalps.ch\/fr\/wp-json\/wp\/v2\/posts\/24971\/revisions\/24979"}],"wp:attachment":[{"href":"https:\/\/proalps.ch\/fr\/wp-json\/wp\/v2\/media?parent=24971"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/proalps.ch\/fr\/wp-json\/wp\/v2\/categories?post=24971"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/proalps.ch\/fr\/wp-json\/wp\/v2\/tags?post=24971"},{"taxonomy":"wf_post_folders","embeddable":true,"href":"https:\/\/proalps.ch\/fr\/wp-json\/wp\/v2\/wf_post_folders?post=24971"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}